{"id":5410,"date":"2023-01-23T14:17:19","date_gmt":"2023-01-23T14:17:19","guid":{"rendered":"https:\/\/nouhefikri.ml\/home-2\/"},"modified":"2024-04-16T14:29:15","modified_gmt":"2024-04-16T14:29:15","slug":"firestick-iptv","status":"publish","type":"page","link":"https:\/\/dgtl-planet.store\/danish_iptv\/firestick-iptv\/","title":{"rendered":"Firestick"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5410_519cc4-86{margin-bottom:0px;}.kb-row-layout-id5410_519cc4-86 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_519cc4-86 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_519cc4-86 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:25%;padding-bottom:0%;min-height:400px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_519cc4-86 > .kt-row-layout-overlay{opacity:0.00;background-color:rgba(115, 13, 13, 0);}@media all and (max-width: 1024px){.kb-row-layout-id5410_519cc4-86 > .kt-row-column-wrap{padding-top:0%;padding-right:0%;padding-bottom:30%;padding-left:0%;min-height:100px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5410_519cc4-86 > .kt-row-column-wrap{min-height:110px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_519cc4-86 alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-blocks-carousel kb-blocks-bg-slider kt-carousel-container-dotstyle-none\"><div class=\"kt-blocks-carousel-init splide kb-blocks-bg-slider-init kt-carousel-arrowstyle-none kt-carousel-dotstyle-none\" data-slider-anim-speed=\"1000\" data-slider-type=\"slider\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"false\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\" data-slider-speed=\"4000\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-0\" style=\"background-image:url(https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/1-3.webp); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-1\" style=\"background-image:url(https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/2-3.webp); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-2\" style=\"background-image:url(https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/3-3.webp); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-3\" style=\"background-image:url(https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/4-3.webp); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><li class=\"splide__slide kb-bg-slide-contain\"><div  class=\"kb-bg-slide kb-bg-slide-4\" style=\"background-image:url(https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/5-3.webp); background-size:cover; background-position:center center; background-repeat:no-repeat;\"><\/div><\/li><\/ul><\/div><\/div><\/div><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full kb-theme-content-width\">\n<style>.kadence-column5410_9fc333-71 > .kt-inside-inner-col,.kadence-column5410_9fc333-71 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_9fc333-71 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_9fc333-71 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_9fc333-71 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_9fc333-71 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_9fc333-71{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_9fc333-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_9fc333-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_9fc333-71 inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5410_3c21eb-71{margin-top:0px;margin-bottom:0px;}.kb-row-layout-id5410_3c21eb-71 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_3c21eb-71 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_3c21eb-71 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_3c21eb-71 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5410_3c21eb-71 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5410_3c21eb-71 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_3c21eb-71 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5410_b1c88a-4f > .kt-inside-inner-col{padding-top:40px;}.kadence-column5410_b1c88a-4f > .kt-inside-inner-col,.kadence-column5410_b1c88a-4f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_b1c88a-4f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_b1c88a-4f > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_b1c88a-4f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_b1c88a-4f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_b1c88a-4f{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_b1c88a-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_b1c88a-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_b1c88a-4f inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\"><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns5410_201e1f-91, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns5410_201e1f-91, .wp-block-kadence-advancedbtn.kb-btns5410_201e1f-91, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns5410_201e1f-91{margin-top:-40px;margin-bottom:-50px;}.wp-block-kadence-advancedbtn.kb-btns5410_201e1f-91{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_201e1f-91 .kt-button{font-weight:normal;font-style:normal;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn.kb-btns5410_201e1f-91{justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn.kb-btns5410_201e1f-91{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_201e1f-91\"><style>.wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button, ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button{width:188px;}.wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button{color:var(--global-palette9, #ffffff);background:#39a8f0;font-weight:bold;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;box-shadow:1px 2px 2px 3px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button:focus{color:var(--global-palette2, #2B6CB0);background:var(--global-palette9, #ffffff);border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;box-shadow:2px 2px 2px 1px var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_6fe0e7-dc.kb-button:focus{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_6fe0e7-dc kt-btn-size-standard kt-btn-width-type-fixed kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"#plans\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">Buy Now<\/span><\/a><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><\/div>\n<\/div>\n\n\n<style>.kb-row-layout-id5410_7d14ec-c8 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_7d14ec-c8 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_7d14ec-c8 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_7d14ec-c8 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5410_7d14ec-c8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5410_7d14ec-c8 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_7d14ec-c8 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5410_eb53fc-dd > .kt-inside-inner-col{border-top:4px solid var(--global-palette1, #3182CE);border-right:4px solid var(--global-palette1, #3182CE);border-bottom:4px solid var(--global-palette1, #3182CE);border-left:4px solid var(--global-palette1, #3182CE);}.kadence-column5410_eb53fc-dd > .kt-inside-inner-col,.kadence-column5410_eb53fc-dd > .kt-inside-inner-col:before{border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;}.kadence-column5410_eb53fc-dd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_eb53fc-dd > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_eb53fc-dd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_eb53fc-dd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_eb53fc-dd{position:relative;}.kadence-column5410_eb53fc-dd, .kt-inside-inner-col > .kadence-column5410_eb53fc-dd:not(.specificity){margin-top:var(--global-kb-spacing-sm, 1.5rem);margin-bottom:0px;}@media all and (max-width: 1024px){.kadence-column5410_eb53fc-dd > .kt-inside-inner-col{border-top:4px solid var(--global-palette1, #3182CE);border-right:4px solid var(--global-palette1, #3182CE);border-bottom:4px solid var(--global-palette1, #3182CE);border-left:4px solid var(--global-palette1, #3182CE);flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_eb53fc-dd > .kt-inside-inner-col{border-top:4px solid var(--global-palette1, #3182CE);border-right:4px solid var(--global-palette1, #3182CE);border-bottom:4px solid var(--global-palette1, #3182CE);border-left:4px solid var(--global-palette1, #3182CE);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_eb53fc-dd\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-carousel-slider-slider\"><div class=\"carousel-slider-outer carousel-slider-outer-image-carousel carousel-slider-outer-6042\" style=\"--carousel-slider-nav-color:rgba(241,241,241,0);--carousel-slider-active-nav-color:rgba(0,209,178,0);--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-6042\" class=\"carousel-slider carousel-slider-6042 arrows-visibility-never dots-visibility-never arrows-outside dots-center dots-circle owl-carousel\" data-slide-type=\"image-carousel\" data-owl-settings='{\"nav\":false,\"dots\":false,\"slideBy\":1,\"stagePadding\":0,\"margin\":10,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":5000,\"autoplaySpeed\":500,\"autoplayHoverPause\":false,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":5},\"576\":{\"items\":6},\"768\":{\"items\":8},\"1024\":{\"items\":9},\"1280\":{\"items\":10},\"1536\":{\"items\":12}}}'>\n<div class=\"carousel-slider__item\">\n\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-24.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-24.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-24-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-24-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-41.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-41.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-41-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-41-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-29.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-29.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-29-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-29-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-33.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-33.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-33-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-33-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-31.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-31.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-31-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-31-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-14.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-14.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-14-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-14-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-42.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-42.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-42-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-42-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-10.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-10.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-10-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-10-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-8.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-8.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-8-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-8-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-28.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-28.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-28-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-28-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-20.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-20.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-20-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-20-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-15.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-15.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-15-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-15-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-3.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-3.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-3-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-3-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-13.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-13.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-13-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-13-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-26.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-26.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-26-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-26-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-12.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-12.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-12-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-12-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-11.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-11.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-11-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-11-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-21.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-21.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-21-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-21-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-4.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-4.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-4-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-4-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-23.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-23.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-23-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-23-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-35.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-35.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-35-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-35-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-37.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-37.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-37-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-37-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-2.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-2-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-2-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-25.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-25.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-25-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-25-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-22.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-22.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-22-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-22-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-34.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-34.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-34-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-34-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-6.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-6.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-6-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-6-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-27.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-27.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-27-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-27-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-1.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-1.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-1-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-1-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-36.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-36.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-36-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-36-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-7.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-7.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-7-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-7-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-40.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-40.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-40-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-40-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-16.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-16.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-16-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-16-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-39.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-39.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-39-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-39-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-38.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-38.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-38-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-38-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-43.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-43.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-43-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-43-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-18.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-18.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-18-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-18-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-19.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-19.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-19-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-19-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-32.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-32.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-32-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-32-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-9.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-9.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-9-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-9-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-30.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-30.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-30-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-30-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-5.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-5.png 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-5-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-5-150x150.png 150w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-17.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-17.png 501w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-17-300x300.png 300w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/01-17-150x150.png 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><\/div>\n\n<\/div><!-- .carousel-slider-6042 -->\n<\/div><!-- .carousel-slider-outer-6042 -->\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id5410_9dc6ae-e1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_9dc6ae-e1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_9dc6ae-e1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:50px;padding-bottom:0px;}.kb-row-layout-id5410_9dc6ae-e1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id5410_9dc6ae-e1 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id5410_9dc6ae-e1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5410_9dc6ae-e1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id5410_9dc6ae-e1 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id5410_9dc6ae-e1 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id5410_9dc6ae-e1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_9dc6ae-e1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column5410_18f386-af > .kt-inside-inner-col,.kadence-column5410_18f386-af > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_18f386-af > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_18f386-af > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_18f386-af > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_18f386-af > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_18f386-af{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_18f386-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_18f386-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_18f386-af inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box5410_48466d-56 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box5410_48466d-56 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:10px;}.kt-info-box5410_48466d-56 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box5410_48466d-56.wp-block-kadence-infobox{max-width:100%;}.kt-info-box5410_48466d-56 .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box5410_48466d-56 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box5410_48466d-56 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box5410_48466d-56 .kt-info-svg-icon-flip, .kt-info-box5410_48466d-56 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box5410_48466d-56 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_48466d-56 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box5410_48466d-56 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_48466d-56 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box5410_48466d-56 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box5410_48466d-56 .kt-blocks-info-box-text{font-size:12px;}.kt-info-box5410_48466d-56 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box5410_48466d-56 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box5410_48466d-56 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box5410_48466d-56 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box5410_48466d-56 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);}}@media all and (max-width: 767px){.kt-info-box5410_48466d-56 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box5410_48466d-56\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2022\/09\/4-min-1.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4373\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>Top Rated Channels<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">Enjoy Top-rated TV channels with the best streaming experience.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_a6389b-4e > .kt-inside-inner-col,.kadence-column5410_a6389b-4e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_a6389b-4e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_a6389b-4e > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_a6389b-4e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_a6389b-4e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_a6389b-4e{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_a6389b-4e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_a6389b-4e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_a6389b-4e inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box5410_abd2d3-9a .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:20px;}.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box5410_abd2d3-9a.wp-block-kadence-infobox{max-width:100%;}.kt-info-box5410_abd2d3-9a .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box5410_abd2d3-9a .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box5410_abd2d3-9a .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box5410_abd2d3-9a .kt-info-svg-icon-flip, .kt-info-box5410_abd2d3-9a .kt-blocks-info-box-number{font-size:50px;}.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box5410_abd2d3-9a .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box5410_abd2d3-9a .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-text{font-size:12px;}.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}@media all and (max-width: 767px){.kt-info-box5410_abd2d3-9a .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box5410_abd2d3-9a\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2022\/09\/3-min-1.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4369\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>Fast Connected<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">Once you sign up whether a Free Trial or a Paid Plan. You get instant access with the same login credentials.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_35b0f9-c9 > .kt-inside-inner-col,.kadence-column5410_35b0f9-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_35b0f9-c9 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_35b0f9-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_35b0f9-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_35b0f9-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_35b0f9-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_35b0f9-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_35b0f9-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_35b0f9-c9 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box5410_8eb399-0f .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box5410_8eb399-0f .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:20px;}.kt-info-box5410_8eb399-0f .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box5410_8eb399-0f.wp-block-kadence-infobox{max-width:100%;}.kt-info-box5410_8eb399-0f .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box5410_8eb399-0f .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box5410_8eb399-0f .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box5410_8eb399-0f .kt-info-svg-icon-flip, .kt-info-box5410_8eb399-0f .kt-blocks-info-box-number{font-size:50px;}.kt-info-box5410_8eb399-0f .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_8eb399-0f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box5410_8eb399-0f .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_8eb399-0f .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box5410_8eb399-0f .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box5410_8eb399-0f .kt-blocks-info-box-text{font-size:12px;}.kt-info-box5410_8eb399-0f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box5410_8eb399-0f .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box5410_8eb399-0f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box5410_8eb399-0f .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box5410_8eb399-0f .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}@media all and (max-width: 767px){.kt-info-box5410_8eb399-0f .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box5410_8eb399-0f\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2022\/09\/2-min-1.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4365\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>Customer Service<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">Get 24 hours 7 days a week Customer Service<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_f7a760-9e > .kt-inside-inner-col,.kadence-column5410_f7a760-9e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_f7a760-9e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_f7a760-9e > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_f7a760-9e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_f7a760-9e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_f7a760-9e{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_f7a760-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_f7a760-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_f7a760-9e inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box5410_781694-5c .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box5410_781694-5c .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:20px;}.kt-info-box5410_781694-5c .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box5410_781694-5c.wp-block-kadence-infobox{max-width:100%;}.kt-info-box5410_781694-5c .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box5410_781694-5c .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box5410_781694-5c .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box5410_781694-5c .kt-info-svg-icon-flip, .kt-info-box5410_781694-5c .kt-blocks-info-box-number{font-size:50px;}.kt-info-box5410_781694-5c .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_781694-5c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box5410_781694-5c .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_781694-5c .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box5410_781694-5c .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box5410_781694-5c .kt-blocks-info-box-text{font-size:12px;}.kt-info-box5410_781694-5c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box5410_781694-5c .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box5410_781694-5c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box5410_781694-5c .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box5410_781694-5c\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2022\/09\/5-min.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4376\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>Best Pricing Plans<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">You will not find a second place to save money with such Quality Standards.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column5410_70d4ff-ca > .kt-inside-inner-col,.kadence-column5410_70d4ff-ca > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_70d4ff-ca > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_70d4ff-ca > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_70d4ff-ca > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_70d4ff-ca > .kt-inside-inner-col{background-color:rgba(49, 130, 206, 0);}.kadence-column5410_70d4ff-ca > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_70d4ff-ca{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_70d4ff-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_70d4ff-ca > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_70d4ff-ca\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id5410_dac619-7a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_dac619-7a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_dac619-7a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_dac619-7a{border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;overflow:clip;isolation:isolate;}.kb-row-layout-id5410_dac619-7a > .kt-row-layout-overlay{border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;}.kb-row-layout-id5410_dac619-7a{border-top:4px solid var(--global-palette1, #3182CE);border-right:4px solid var(--global-palette1, #3182CE);border-bottom:4px solid var(--global-palette1, #3182CE);border-left:4px solid var(--global-palette1, #3182CE);}.kb-row-layout-id5410_dac619-7a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5410_dac619-7a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id5410_dac619-7a{border-top:4px solid var(--global-palette1, #3182CE);border-right:4px solid var(--global-palette1, #3182CE);border-bottom:4px solid var(--global-palette1, #3182CE);border-left:4px solid var(--global-palette1, #3182CE);}}@media all and (max-width: 767px){.kb-row-layout-id5410_dac619-7a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_dac619-7a{border-top:4px solid var(--global-palette1, #3182CE);border-right:4px solid var(--global-palette1, #3182CE);border-bottom:4px solid var(--global-palette1, #3182CE);border-left:4px solid var(--global-palette1, #3182CE);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_dac619-7a alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5410_c7492e-cb > .kt-inside-inner-col,.kadence-column5410_c7492e-cb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_c7492e-cb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_c7492e-cb > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_c7492e-cb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_c7492e-cb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_c7492e-cb{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_c7492e-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_c7492e-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_c7492e-cb\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-carousel-slider-slider\"><div class=\"carousel-slider-outer carousel-slider-outer-image-carousel carousel-slider-outer-6093\" style=\"--carousel-slider-nav-color:rgba(241,241,241,0);--carousel-slider-active-nav-color:rgba(0,209,178,0);--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-6093\" class=\"carousel-slider carousel-slider-6093 arrows-visibility-hover dots-visibility-never arrows-outside dots-center dots-circle owl-carousel\" data-slide-type=\"image-carousel\" data-owl-settings='{\"nav\":true,\"dots\":false,\"slideBy\":1,\"stagePadding\":0,\"margin\":10,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":1500,\"autoplaySpeed\":700,\"autoplayHoverPause\":false,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":2},\"576\":{\"items\":3},\"768\":{\"items\":3},\"1024\":{\"items\":4},\"1280\":{\"items\":5},\"1536\":{\"items\":5}}}'>\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Hotel-Portofino-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Hotel-Portofino-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Hotel-Portofino-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Menu-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Menu-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Menu-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Black-Mirror-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Black-Mirror-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Black-Mirror-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/elvis-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/elvis-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/elvis-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Top-Gear-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Top-Gear-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Top-Gear-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Batman-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Batman-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Batman-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Last-Night-in-Soho-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Last-Night-in-Soho-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Last-Night-in-Soho-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Spencer-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Spencer-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Spencer-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-355-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-355-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-355-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Heartstopper-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Heartstopper-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Heartstopper-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Last-Duel-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Last-Duel-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Last-Duel-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Bubble-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Bubble-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Bubble-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Responder-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Responder-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Responder-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/SAS-Rogue-Heroes-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/SAS-Rogue-Heroes-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/SAS-Rogue-Heroes-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Avatar-2-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Avatar-2-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Avatar-2-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Fate-The-Winx-Saga-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Fate-The-Winx-Saga-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Fate-The-Winx-Saga-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/His-Dark-Materials-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/His-Dark-Materials-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/His-Dark-Materials-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Killing-Eve-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Killing-Eve-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Killing-Eve-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-English-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-English-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-English-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Fantastic-Beasts-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Fantastic-Beasts-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Fantastic-Beasts-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/No-Time-to-Die-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/No-Time-to-Die-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/No-Time-to-Die-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Line-of-Duty-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Line-of-Duty-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Line-of-Duty-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-End-of-the-Fucking-World-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-End-of-the-Fucking-World-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-End-of-the-Fucking-World-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Last-Kingdom-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Last-Kingdom-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Last-Kingdom-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Mr.-Bean-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Mr.-Bean-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Mr.-Bean-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Red-Notice-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Red-Notice-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Red-Notice-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Northman-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Northman-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Northman-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Stay-Close-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Stay-Close-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Stay-Close-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Aquaman-and-the-Lost-Kingdom-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Aquaman-and-the-Lost-Kingdom-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Aquaman-and-the-Lost-Kingdom-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Doc-Martin-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Doc-Martin-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Doc-Martin-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Man-in-the-High-Castle-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Man-in-the-High-Castle-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Man-in-the-High-Castle-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Sonic-the-Hedgehog-2-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Sonic-the-Hedgehog-2-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Sonic-the-Hedgehog-2-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Thor-Love-and-Thunder-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Thor-Love-and-Thunder-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Thor-Love-and-Thunder-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Fleabag-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Fleabag-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Fleabag-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Malignant-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Malignant-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Malignant-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Clarksons-Farm-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Clarksons-Farm-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Clarksons-Farm-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Derry-Girls-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Derry-Girls-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Derry-Girls-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Good-Omens-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Good-Omens-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Good-Omens-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/White-Lines-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/White-Lines-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/White-Lines-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Black-Adam-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Black-Adam-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Black-Adam-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Jurassic-World-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Jurassic-World-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Jurassic-World-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Ghosts-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Ghosts-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Ghosts-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Crown-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Crown-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Crown-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Happy-Valley-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Happy-Valley-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Happy-Valley-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-French-Dispatch-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-French-Dispatch-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-French-Dispatch-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Inside-Man-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Inside-Man-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Inside-Man-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Sandman-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Sandman-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Sandman-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Indiana-Jones-5-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Indiana-Jones-5-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Indiana-Jones-5-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Black-Panther-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Black-Panther-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Black-Panther-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Lost-City-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Lost-City-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Lost-City-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Broadchurch-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Broadchurch-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Broadchurch-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Detectorists-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Detectorists-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Detectorists-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/After-Life-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/After-Life-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/After-Life-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Endeavour-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Endeavour-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Endeavour-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Bad-Sisters-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Bad-Sisters-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Bad-Sisters-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Card-Counter-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Card-Counter-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Card-Counter-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Bad-Guys-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Bad-Guys-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Bad-Guys-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Nevers-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Nevers-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Nevers-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Doctor-Strange-in-the-Multiverse-of-Madness-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Doctor-Strange-in-the-Multiverse-of-Madness-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Doctor-Strange-in-the-Multiverse-of-Madness-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Devils-Hour-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Devils-Hour-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Devils-Hour-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Man-vs.-Bee-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Man-vs.-Bee-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Man-vs.-Bee-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Game-of-Thrones-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Game-of-Thrones-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Game-of-Thrones-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/This-Is-Going-to-Hurt-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/This-Is-Going-to-Hurt-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/This-Is-Going-to-Hurt-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Many-Saints-of-Newark-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Many-Saints-of-Newark-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Many-Saints-of-Newark-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Nightingale-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Nightingale-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Nightingale-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Power-of-the-Dog-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Power-of-the-Dog-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Power-of-the-Dog-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Luther-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Luther-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Luther-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Cyrano-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Cyrano-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Cyrano-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Unbearable-Weight-of-Massive-Talent-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Unbearable-Weight-of-Massive-Talent-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Unbearable-Weight-of-Massive-Talent-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Benediction-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Benediction-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Benediction-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Prison-Break-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Prison-Break-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Prison-Break-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Peaky-Blinders-imdb-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Peaky-Blinders-imdb-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Peaky-Blinders-imdb-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Puss-in-Boots-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Puss-in-Boots-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Puss-in-Boots-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Matilda-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Matilda-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Matilda-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Slow-Horses-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Slow-Horses-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Slow-Horses-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/A-Discovery-of-Witches-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/A-Discovery-of-Witches-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/A-Discovery-of-Witches-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/the-god-father-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/the-god-father-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/the-god-father-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Mission-Impossible-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Mission-Impossible-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Mission-Impossible-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Tourist-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Tourist-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/The-Tourist-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"750\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Nightmare-Alley-min.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Nightmare-Alley-min.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/04\/Nightmare-Alley-min-200x300.webp 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<\/div><!-- .carousel-slider-6093 -->\n<\/div><!-- .carousel-slider-outer-6093 -->\n<\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kb-row-layout-id5410_3cefce-6d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_3cefce-6d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_3cefce-6d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-none, 0rem );row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:0px;}.kb-row-layout-id5410_3cefce-6d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id5410_3cefce-6d > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id5410_3cefce-6d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5410_3cefce-6d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id5410_3cefce-6d > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id5410_3cefce-6d > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id5410_3cefce-6d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_3cefce-6d alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column5410_c052b0-89 > .kt-inside-inner-col,.kadence-column5410_c052b0-89 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_c052b0-89 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_c052b0-89 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_c052b0-89 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_c052b0-89 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_c052b0-89{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_c052b0-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_c052b0-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_c052b0-89 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box5410_f38a70-96 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box5410_f38a70-96 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:10px;}.kt-info-box5410_f38a70-96 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box5410_f38a70-96.wp-block-kadence-infobox{max-width:100%;}.kt-info-box5410_f38a70-96 .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box5410_f38a70-96 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box5410_f38a70-96 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box5410_f38a70-96 .kt-info-svg-icon-flip, .kt-info-box5410_f38a70-96 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box5410_f38a70-96 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_f38a70-96 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box5410_f38a70-96 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_f38a70-96 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box5410_f38a70-96 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box5410_f38a70-96 .kt-blocks-info-box-text{font-size:12px;}.kt-info-box5410_f38a70-96 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box5410_f38a70-96 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box5410_f38a70-96 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box5410_f38a70-96 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box5410_f38a70-96 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);}}@media all and (max-width: 767px){.kt-info-box5410_f38a70-96 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(7, 7, 7, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box5410_f38a70-96\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2022\/09\/6-min.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4379\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>67000+ VOD<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">More than 67000 VOD films and series in multiple languages.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_6a86c7-8d > .kt-inside-inner-col,.kadence-column5410_6a86c7-8d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_6a86c7-8d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_6a86c7-8d > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_6a86c7-8d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_6a86c7-8d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_6a86c7-8d{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_6a86c7-8d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_6a86c7-8d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_6a86c7-8d inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box5410_36db08-55 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box5410_36db08-55 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:20px;}.kt-info-box5410_36db08-55 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box5410_36db08-55.wp-block-kadence-infobox{max-width:100%;}.kt-info-box5410_36db08-55 .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box5410_36db08-55 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box5410_36db08-55 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box5410_36db08-55 .kt-info-svg-icon-flip, .kt-info-box5410_36db08-55 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box5410_36db08-55 .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_36db08-55 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box5410_36db08-55 .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_36db08-55 .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box5410_36db08-55 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box5410_36db08-55 .kt-blocks-info-box-text{font-size:12px;}.kt-info-box5410_36db08-55 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box5410_36db08-55 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box5410_36db08-55 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box5410_36db08-55 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box5410_36db08-55 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}@media all and (max-width: 767px){.kt-info-box5410_36db08-55 .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box5410_36db08-55\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2022\/09\/1-min-1.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4362\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>19000+ CHANNELS<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">Full customizable channel list.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_7a3186-59 > .kt-inside-inner-col,.kadence-column5410_7a3186-59 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_7a3186-59 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_7a3186-59 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_7a3186-59 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_7a3186-59 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_7a3186-59{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_7a3186-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_7a3186-59 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_7a3186-59 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box5410_a62307-5d .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box5410_a62307-5d .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:20px;padding-bottom:10px;padding-left:20px;}.kt-info-box5410_a62307-5d .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box5410_a62307-5d.wp-block-kadence-infobox{max-width:100%;}.kt-info-box5410_a62307-5d .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box5410_a62307-5d .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box5410_a62307-5d .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box5410_a62307-5d .kt-info-svg-icon-flip, .kt-info-box5410_a62307-5d .kt-blocks-info-box-number{font-size:50px;}.kt-info-box5410_a62307-5d .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_a62307-5d .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box5410_a62307-5d .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_a62307-5d .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box5410_a62307-5d .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box5410_a62307-5d .kt-blocks-info-box-text{font-size:12px;}.kt-info-box5410_a62307-5d .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box5410_a62307-5d .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box5410_a62307-5d .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box5410_a62307-5d .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box5410_a62307-5d .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}@media all and (max-width: 767px){.kt-info-box5410_a62307-5d .kt-blocks-info-box-link-wrap{border-right:1px solid rgba(0, 0, 0, 0.04);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box5410_a62307-5d\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2022\/09\/10-min.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4384\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>99.99% UPTIME<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">All live channels are 99.99% uptime.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_7a44b2-cb > .kt-inside-inner-col,.kadence-column5410_7a44b2-cb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_7a44b2-cb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_7a44b2-cb > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_7a44b2-cb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_7a44b2-cb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_7a44b2-cb{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_7a44b2-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_7a44b2-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_7a44b2-cb inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box5410_676ba2-8c .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box5410_676ba2-8c .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(242, 242, 242, 0);padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:20px;}.kt-info-box5410_676ba2-8c .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box5410_676ba2-8c.wp-block-kadence-infobox{max-width:100%;}.kt-info-box5410_676ba2-8c .kadence-info-box-image-inner-intrisic-container{max-width:50px;}.kt-info-box5410_676ba2-8c .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:100%;width:86px;height:0px;max-width:100%;}.kt-info-box5410_676ba2-8c .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box5410_676ba2-8c .kt-info-svg-icon-flip, .kt-info-box5410_676ba2-8c .kt-blocks-info-box-number{font-size:50px;}.kt-info-box5410_676ba2-8c .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:15px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_676ba2-8c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:#444444;background:transparent;border-color:#444444;}.kt-info-box5410_676ba2-8c .kt-infobox-textcontent h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:14px;font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-info-box5410_676ba2-8c .kt-blocks-info-box-link-wrap:hover h2.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);}.kt-info-box5410_676ba2-8c .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.wp-block-kadence-infobox.kt-info-box5410_676ba2-8c .kt-blocks-info-box-text{font-size:12px;}.kt-info-box5410_676ba2-8c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette5, #4A5568);}.kt-info-box5410_676ba2-8c .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box5410_676ba2-8c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box5410_676ba2-8c .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box5410_676ba2-8c\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2022\/09\/8-min.webp\" alt=\"\" width=\"86\" height=\"86\" class=\"kt-info-box-image wp-image-4381\"\/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h2 class=\"kt-blocks-info-box-title\"><strong>Refund Guaranteed<\/strong><\/h2><p class=\"kt-blocks-info-box-text\">check our <a href=\"https:\/\/dgtl-planet.store\/refund_returns\/\" data-type=\"URL\" data-id=\"https:\/\/prim-iptv.com\/refund_returns\/\">refund policy<\/a>.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5410_deed6b-8c{margin-top:-20px;}.kb-row-layout-id5410_deed6b-8c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_deed6b-8c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_deed6b-8c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_deed6b-8c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5410_deed6b-8c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5410_deed6b-8c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_deed6b-8c alignnone wp-block-kadence-rowlayout\" id=\"plans\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column5410_80f47c-37 > .kt-inside-inner-col,.kadence-column5410_80f47c-37 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_80f47c-37 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_80f47c-37 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_80f47c-37 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_80f47c-37 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_80f47c-37{position:relative;}.kadence-column5410_80f47c-37, .kt-inside-inner-col > .kadence-column5410_80f47c-37:not(.specificity){margin-top:-20px;}@media all and (max-width: 1024px){.kadence-column5410_80f47c-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_80f47c-37 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_80f47c-37 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id5410_5188b3-26 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_5188b3-26 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_5188b3-26 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:700px;margin-left:auto;margin-right:auto;padding-top:0px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_5188b3-26 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5410_5188b3-26 > .kt-row-column-wrap{padding-top:0px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5410_5188b3-26 > .kt-row-column-wrap{padding-top:0px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_5188b3-26 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5410_9ed982-ae > .kt-inside-inner-col{padding-top:40px;}.kadence-column5410_9ed982-ae > .kt-inside-inner-col,.kadence-column5410_9ed982-ae > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_9ed982-ae > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_9ed982-ae > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_9ed982-ae > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_9ed982-ae > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_9ed982-ae{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_9ed982-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_9ed982-ae > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_9ed982-ae inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading5410_cfae59-29, .wp-block-kadence-advancedheading.kt-adv-heading5410_cfae59-29[data-kb-block=\"kb-adv-heading5410_cfae59-29\"]{padding-bottom:var(--global-kb-spacing-xs, 1rem);margin-top:10px;margin-bottom:40px;text-align:center;font-size:50px;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading5410_cfae59-29 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_cfae59-29[data-kb-block=\"kb-adv-heading5410_cfae59-29\"] mark.kt-highlight{font-weight:normal;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_cfae59-29 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_cfae59-29[data-kb-block=\"kb-adv-heading5410_cfae59-29\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading5410_cfae59-29, .wp-block-kadence-advancedheading.kt-adv-heading5410_cfae59-29[data-kb-block=\"kb-adv-heading5410_cfae59-29\"]{font-size:40px;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading5410_cfae59-29, .wp-block-kadence-advancedheading.kt-adv-heading5410_cfae59-29[data-kb-block=\"kb-adv-heading5410_cfae59-29\"]{font-size:30px;}}<\/style>\n<h2 class=\"kt-adv-heading5410_cfae59-29 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading5410_cfae59-29\">Choose A Subscription Plan<\/h2>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id5410_c7a8a8-e5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_c7a8a8-e5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_c7a8a8-e5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0%;padding-bottom:0%;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_c7a8a8-e5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id5410_c7a8a8-e5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5410_c7a8a8-e5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_c7a8a8-e5 alignwide wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5410_594c99-ee > .kt-inside-inner-col{padding-top:0%;padding-right:20%;padding-left:20%;}.kadence-column5410_594c99-ee > .kt-inside-inner-col,.kadence-column5410_594c99-ee > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_594c99-ee > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_594c99-ee > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_594c99-ee > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_594c99-ee > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_594c99-ee{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_594c99-ee > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_594c99-ee > .kt-inside-inner-col{padding-right:5%;padding-left:5%;flex-direction:column;justify-content:center;}.kadence-column5410_594c99-ee, .kt-inside-inner-col > .kadence-column5410_594c99-ee:not(.specificity){margin-right:0px;margin-left:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_594c99-ee kvs-lg-false kvs-md-false kvs-sm-false inner-column-1\"><div class=\"kt-inside-inner-col\"><\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kadence-column5410_71adda-15 > .kt-inside-inner-col,.kadence-column5410_71adda-15 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_71adda-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_71adda-15 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_71adda-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_71adda-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_71adda-15{position:relative;}.kadence-column5410_71adda-15, .kt-inside-inner-col > .kadence-column5410_71adda-15:not(.specificity){margin-top:-50px;}@media all and (max-width: 1024px){.kadence-column5410_71adda-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_71adda-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_71adda-15 kvs-md-false kvs-sm-false inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5410_7c1553-dd{margin-top:-40px;}.kb-row-layout-id5410_7c1553-dd > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_7c1553-dd > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_7c1553-dd > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-bottom:100px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_7c1553-dd{background-image:url('https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/02\/familywatachingtv.webp');background-size:cover;background-position:50% 100%;background-attachment:fixed;background-repeat:no-repeat;}.kb-row-layout-id5410_7c1553-dd > .kt-row-layout-overlay{opacity:1;background:linear-gradient(180deg, var(--global-palette9) 0%, rgba(26, 32, 44, 0) 45%);mix-blend-mode:normal;}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-id5410_7c1553-dd{background-attachment:scroll;}}@media all and (max-width: 1024px){.kb-row-layout-id5410_7c1553-dd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5410_7c1553-dd > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}.kb-row-layout-id5410_7c1553-dd {}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_7c1553-dd alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column5410_adf7b7-03 > .kt-inside-inner-col{display:flex;}.kadence-column5410_adf7b7-03 > .kt-inside-inner-col,.kadence-column5410_adf7b7-03 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_adf7b7-03 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_adf7b7-03 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column5410_adf7b7-03 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column5410_adf7b7-03{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_adf7b7-03{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_adf7b7-03 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column5410_adf7b7-03 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_adf7b7-03{position:relative;}.kadence-column5410_adf7b7-03, .kt-inside-inner-col > .kadence-column5410_adf7b7-03:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column5410_adf7b7-03{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_adf7b7-03{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_adf7b7-03 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column5410_adf7b7-03 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column5410_adf7b7-03{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_adf7b7-03{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_adf7b7-03 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column5410_adf7b7-03 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_adf7b7-03 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-group alignfull\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.kb-row-layout-id5410_fcc533-b2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_fcc533-b2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_fcc533-b2 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1196px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id5410_fcc533-b2 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id5410_fcc533-b2 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id5410_fcc533-b2 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id5410_fcc533-b2 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id5410_fcc533-b2 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id5410_fcc533-b2 .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id5410_fcc533-b2 > .kt-row-column-wrap{max-width:600px;margin-left:auto;margin-right:auto;grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id5410_fcc533-b2 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id5410_fcc533-b2 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id5410_fcc533-b2 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id5410_fcc533-b2 > .kt-row-column-wrap{max-width:290px;margin-left:auto;margin-right:auto;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_fcc533-b2 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id5410_fcc533-b2 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id5410_fcc533-b2 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_fcc533-b2 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column5410_d1f79c-5d > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column5410_d1f79c-5d > .kt-inside-inner-col,.kadence-column5410_d1f79c-5d > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column5410_d1f79c-5d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_d1f79c-5d > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_d1f79c-5d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_d1f79c-5d > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column5410_d1f79c-5d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_d1f79c-5d{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_d1f79c-5d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_d1f79c-5d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_d1f79c-5d inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading5410_958fb1-c6, .wp-block-kadence-advancedheading.kt-adv-heading5410_958fb1-c6[data-kb-block=\"kb-adv-heading5410_958fb1-c6\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading5410_958fb1-c6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_958fb1-c6[data-kb-block=\"kb-adv-heading5410_958fb1-c6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_958fb1-c6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_958fb1-c6[data-kb-block=\"kb-adv-heading5410_958fb1-c6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading5410_958fb1-c6 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_958fb1-c6\">1 Month<\/h6>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-3-color has-text-color\"><s>\u00a315<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5410_dac5e9-d0, .wp-block-kadence-advancedheading.kt-adv-heading5410_dac5e9-d0[data-kb-block=\"kb-adv-heading5410_dac5e9-d0\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading5410_dac5e9-d0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_dac5e9-d0[data-kb-block=\"kb-adv-heading5410_dac5e9-d0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_dac5e9-d0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_dac5e9-d0[data-kb-block=\"kb-adv-heading5410_dac5e9-d0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading5410_dac5e9-d0 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_dac5e9-d0\"><strong>\u00a39.99<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_4bf63b-09:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_4bf63b-09 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_4bf63b-09 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_4bf63b-09 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items5410_4bf63b-09 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5410_4bf63b-09 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5410_4bf63b-09 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5410_0f4d20-37 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_0f4d20-37 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_0f4d20-37 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_618b22-76 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_618b22-76 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_618b22-76 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_4ca62d-2f .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_4ca62d-2f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_4ca62d-2f kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_a7b088-bd .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_a7b088-bd .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_a7b088-bd kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_4d2c9c-5c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_4d2c9c-5c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_4d2c9c-5c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_039b58-90 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_039b58-90 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_039b58-90 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_1c8e4a-1f .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_1c8e4a-1f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_1c8e4a-1f kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze Technology<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_e40235-1a .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_e40235-1a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_e40235-1a kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_05cca4-08 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_05cca4-08 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_05cca4-08 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns5410_f0bc10-41{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_f0bc10-41 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_f0bc10-41\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_e01a3a-d1.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_e01a3a-d1.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_e01a3a-d1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_e01a3a-d1.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_e01a3a-d1.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_e01a3a-d1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_e01a3a-d1.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_e01a3a-d1.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_e01a3a-d1.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_e01a3a-d1.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_e01a3a-d1 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-outline  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/dgtlplanet.co.uk\/shop\/?add-to-cart=2026\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">BUY NOW<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_0f40ab-3c > .kt-inside-inner-col,.kadence-column5410_0f40ab-3c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_0f40ab-3c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_0f40ab-3c > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_0f40ab-3c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_0f40ab-3c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_0f40ab-3c{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_0f40ab-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_0f40ab-3c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_0f40ab-3c inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column5410_b63662-25 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column5410_b63662-25 > .kt-inside-inner-col,.kadence-column5410_b63662-25 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column5410_b63662-25 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_b63662-25 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_b63662-25 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_b63662-25 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column5410_b63662-25 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_b63662-25{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_b63662-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_b63662-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_b63662-25 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading5410_91d363-80, .wp-block-kadence-advancedheading.kt-adv-heading5410_91d363-80[data-kb-block=\"kb-adv-heading5410_91d363-80\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading5410_91d363-80 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_91d363-80[data-kb-block=\"kb-adv-heading5410_91d363-80\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_91d363-80 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_91d363-80[data-kb-block=\"kb-adv-heading5410_91d363-80\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading5410_91d363-80 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_91d363-80\">3 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center\"><s><s>\u00a3<\/s>30<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5410_7f72e8-d9, .wp-block-kadence-advancedheading.kt-adv-heading5410_7f72e8-d9[data-kb-block=\"kb-adv-heading5410_7f72e8-d9\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading5410_7f72e8-d9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_7f72e8-d9[data-kb-block=\"kb-adv-heading5410_7f72e8-d9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_7f72e8-d9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_7f72e8-d9[data-kb-block=\"kb-adv-heading5410_7f72e8-d9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading5410_7f72e8-d9 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_7f72e8-d9\"><strong>\u00a320<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_d42abb-6c:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_d42abb-6c ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_d42abb-6c ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_d42abb-6c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items5410_d42abb-6c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5410_d42abb-6c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5410_d42abb-6c kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5410_842249-80 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_842249-80 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_842249-80 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_1b20ff-24 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_1b20ff-24 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_1b20ff-24 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_2c2e7b-ae .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_2c2e7b-ae .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_2c2e7b-ae kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_d6be75-99 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_d6be75-99 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_d6be75-99 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_a483eb-5a .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_a483eb-5a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_a483eb-5a kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_794bb1-19 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_794bb1-19 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_794bb1-19 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_2ec82f-38 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_2ec82f-38 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_2ec82f-38 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze Technology<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_406430-89 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_406430-89 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_406430-89 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_39d143-91 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_39d143-91 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_39d143-91 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns5410_17d160-eb{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_17d160-eb .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_17d160-eb\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_84f58e-c7.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_84f58e-c7.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_84f58e-c7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_84f58e-c7.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_84f58e-c7.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_84f58e-c7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_84f58e-c7.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_84f58e-c7.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_84f58e-c7.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_84f58e-c7.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_84f58e-c7 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-outline  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/dgtlplanet.co.uk\/shop\/?add-to-cart=1237\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">BUY NOW<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_ff7694-e8 > .kt-inside-inner-col,.kadence-column5410_ff7694-e8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_ff7694-e8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_ff7694-e8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_ff7694-e8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_ff7694-e8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_ff7694-e8{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_ff7694-e8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_ff7694-e8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_ff7694-e8 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kadence-column5410_8d14c7-5c > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column5410_8d14c7-5c > .kt-inside-inner-col,.kadence-column5410_8d14c7-5c > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column5410_8d14c7-5c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_8d14c7-5c > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_8d14c7-5c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_8d14c7-5c > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column5410_8d14c7-5c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_8d14c7-5c{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_8d14c7-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_8d14c7-5c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_8d14c7-5c inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading5410_dac50a-60, .wp-block-kadence-advancedheading.kt-adv-heading5410_dac50a-60[data-kb-block=\"kb-adv-heading5410_dac50a-60\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading5410_dac50a-60 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_dac50a-60[data-kb-block=\"kb-adv-heading5410_dac50a-60\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_dac50a-60 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_dac50a-60[data-kb-block=\"kb-adv-heading5410_dac50a-60\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading5410_dac50a-60 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_dac50a-60\">6 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center\"><s><s>\u00a3<\/s>45<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5410_c2a940-77, .wp-block-kadence-advancedheading.kt-adv-heading5410_c2a940-77[data-kb-block=\"kb-adv-heading5410_c2a940-77\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading5410_c2a940-77 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_c2a940-77[data-kb-block=\"kb-adv-heading5410_c2a940-77\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_c2a940-77 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_c2a940-77[data-kb-block=\"kb-adv-heading5410_c2a940-77\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading5410_c2a940-77 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_c2a940-77\"><strong>\u00a340<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_573252-8e:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_573252-8e ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_573252-8e ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_573252-8e ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items5410_573252-8e ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5410_573252-8e ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5410_573252-8e kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5410_c16761-2d .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_c16761-2d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_c16761-2d kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_d7595c-aa .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_d7595c-aa .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_d7595c-aa kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_1ab36a-11 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_1ab36a-11 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_1ab36a-11 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_bb3094-0c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_bb3094-0c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_bb3094-0c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_59d886-18 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_59d886-18 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_59d886-18 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_0356d1-f1 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_0356d1-f1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_0356d1-f1 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_c48859-4e .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_c48859-4e .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_c48859-4e kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze Technology<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_754f5d-bc .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_754f5d-bc .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_754f5d-bc kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_e89cfa-2c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_e89cfa-2c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_e89cfa-2c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns5410_d42adf-d1{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_d42adf-d1 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_d42adf-d1\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_897098-6b.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_897098-6b.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_897098-6b.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_897098-6b.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_897098-6b.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_897098-6b.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_897098-6b.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_897098-6b.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_897098-6b.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_897098-6b.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_897098-6b kt-btn-size-large kt-btn-width-type-auto kb-btn-global-outline  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/dgtlplanet.co.uk\/shop\/?add-to-cart=1238\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">BUY NOW<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_f6e413-bb > .kt-inside-inner-col,.kadence-column5410_f6e413-bb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_f6e413-bb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_f6e413-bb > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_f6e413-bb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_f6e413-bb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_f6e413-bb{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_f6e413-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_f6e413-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_f6e413-bb inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.kadence-column5410_25491c-53 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column5410_25491c-53 > .kt-inside-inner-col,.kadence-column5410_25491c-53 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column5410_25491c-53 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_25491c-53 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_25491c-53 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_25491c-53 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column5410_25491c-53 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_25491c-53{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_25491c-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_25491c-53 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_25491c-53 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading5410_90a0f3-25, .wp-block-kadence-advancedheading.kt-adv-heading5410_90a0f3-25[data-kb-block=\"kb-adv-heading5410_90a0f3-25\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading5410_90a0f3-25 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_90a0f3-25[data-kb-block=\"kb-adv-heading5410_90a0f3-25\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_90a0f3-25 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_90a0f3-25[data-kb-block=\"kb-adv-heading5410_90a0f3-25\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading5410_90a0f3-25 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_90a0f3-25\">12 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center\"><s><s>\u00a3<\/s>70<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5410_9039ce-ee, .wp-block-kadence-advancedheading.kt-adv-heading5410_9039ce-ee[data-kb-block=\"kb-adv-heading5410_9039ce-ee\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading5410_9039ce-ee mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_9039ce-ee[data-kb-block=\"kb-adv-heading5410_9039ce-ee\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_9039ce-ee img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_9039ce-ee[data-kb-block=\"kb-adv-heading5410_9039ce-ee\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading5410_9039ce-ee wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_9039ce-ee\"><strong>\u00a350<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_f49860-a7:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_f49860-a7 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_f49860-a7 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_f49860-a7 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items5410_f49860-a7 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5410_f49860-a7 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5410_f49860-a7 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5410_ef76fa-8a .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_ef76fa-8a .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_ef76fa-8a kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">67000+ VOD<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_32358e-a2 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_32358e-a2 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_32358e-a2 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">19000+ CHANNELS<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_23886f-43 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_23886f-43 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_23886f-43 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_0a3e97-3f .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_0a3e97-3f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_0a3e97-3f kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_034a7d-39 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_034a7d-39 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_034a7d-39 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_92cb87-d5 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_92cb87-d5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_92cb87-d5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_1ff532-2c .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_1ff532-2c .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_1ff532-2c kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze Technology<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_e979b5-c6 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_e979b5-c6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_e979b5-c6 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">99% Server Uptime<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_4c4894-40 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_4c4894-40 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_4c4894-40 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">24\/7 support<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns5410_34a829-94{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_34a829-94 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_34a829-94\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_b5cdc9-d5.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_b5cdc9-d5.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_b5cdc9-d5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_b5cdc9-d5.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_b5cdc9-d5.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_b5cdc9-d5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_b5cdc9-d5.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_b5cdc9-d5.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_b5cdc9-d5.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_b5cdc9-d5.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_b5cdc9-d5 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-outline  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/dgtlplanet.co.uk\/shop\/?add-to-cart=1239\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">BUY NOW<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns5410_ce9e99-b9, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns5410_ce9e99-b9, .wp-block-kadence-advancedbtn.kb-btns5410_ce9e99-b9, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns5410_ce9e99-b9{margin-top:-40px;margin-bottom:-50px;}.wp-block-kadence-advancedbtn.kb-btns5410_ce9e99-b9{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_ce9e99-b9 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_ce9e99-b9\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_160f62-70.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_160f62-70.kb-button{color:var(--global-palette1, #3182CE);background:var(--global-palette9, #ffffff);font-weight:bold;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_160f62-70.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_160f62-70.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-top-color:rgba(178, 85, 198, 0);border-top-style:solid;border-right-color:rgba(178, 85, 198, 0);border-right-style:solid;border-bottom-color:rgba(178, 85, 198, 0);border-bottom-style:solid;border-left-color:rgba(178, 85, 198, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_160f62-70.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_160f62-70.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_160f62-70.kb-button:focus{border-top-color:rgba(178, 85, 198, 0);border-top-style:solid;border-right-color:rgba(178, 85, 198, 0);border-right-style:solid;border-bottom-color:rgba(178, 85, 198, 0);border-bottom-style:solid;border-left-color:rgba(178, 85, 198, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_160f62-70.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_160f62-70.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_160f62-70.kb-button:focus{border-top-color:rgba(178, 85, 198, 0);border-top-style:solid;border-right-color:rgba(178, 85, 198, 0);border-right-style:solid;border-bottom-color:rgba(178, 85, 198, 0);border-bottom-style:solid;border-left-color:rgba(178, 85, 198, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_160f62-70 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"\/shop\/\"><span class=\"kt-btn-inner-text\">More Devices<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column5410_6925d1-9e > .kt-inside-inner-col,.kadence-column5410_6925d1-9e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_6925d1-9e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_6925d1-9e > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_6925d1-9e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_6925d1-9e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_6925d1-9e{position:relative;}.kadence-column5410_6925d1-9e, .kt-inside-inner-col > .kadence-column5410_6925d1-9e:not(.specificity){margin-top:-50px;}@media all and (max-width: 1024px){.kadence-column5410_6925d1-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_6925d1-9e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_6925d1-9e kvs-lg-false inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id5410_9f2f31-df{margin-top:-40px;}.kb-row-layout-id5410_9f2f31-df > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_9f2f31-df > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_9f2f31-df > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-bottom:100px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_9f2f31-df{background-image:url('https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/02\/familywatachingtv.webp');background-size:cover;background-position:50% 100%;background-attachment:fixed;background-repeat:no-repeat;}.kb-row-layout-id5410_9f2f31-df > .kt-row-layout-overlay{opacity:1;background:linear-gradient(180deg, var(--global-palette9) 0%, rgba(26, 32, 44, 0) 45%);mix-blend-mode:normal;}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-id5410_9f2f31-df{background-attachment:scroll;}}@media all and (max-width: 1024px){.kb-row-layout-id5410_9f2f31-df > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id5410_9f2f31-df > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}.kb-row-layout-id5410_9f2f31-df {}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_9f2f31-df alignfull kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column5410_906dfd-79 > .kt-inside-inner-col{display:flex;}.kadence-column5410_906dfd-79 > .kt-inside-inner-col,.kadence-column5410_906dfd-79 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_906dfd-79 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_906dfd-79 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column5410_906dfd-79 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column5410_906dfd-79{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_906dfd-79{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_906dfd-79 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column5410_906dfd-79 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_906dfd-79{position:relative;}.kadence-column5410_906dfd-79, .kt-inside-inner-col > .kadence-column5410_906dfd-79:not(.specificity){margin-right:0px;margin-left:0px;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column5410_906dfd-79{align-self:flex-start;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_906dfd-79{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_906dfd-79 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 1024px){.kadence-column5410_906dfd-79 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column5410_906dfd-79{align-self:flex-start;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_906dfd-79{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column5410_906dfd-79 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}.kadence-column5410_906dfd-79 > .kt-inside-inner-col{flex-direction:column;justify-content:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_906dfd-79 kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-group alignfull\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns alignfull is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.kb-row-layout-id5410_a860dc-4b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id5410_a860dc-4b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id5410_a860dc-4b > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1200px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id5410_a860dc-4b > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id5410_a860dc-4b > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id5410_a860dc-4b > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id5410_a860dc-4b .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id5410_a860dc-4b .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id5410_a860dc-4b .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id5410_a860dc-4b > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id5410_a860dc-4b > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id5410_a860dc-4b .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id5410_a860dc-4b .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id5410_a860dc-4b > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id5410_a860dc-4b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id5410_a860dc-4b .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id5410_a860dc-4b .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id5410_a860dc-4b alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-two-grid kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column5410_0e9624-82 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column5410_0e9624-82 > .kt-inside-inner-col,.kadence-column5410_0e9624-82 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column5410_0e9624-82 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_0e9624-82 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_0e9624-82 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_0e9624-82 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column5410_0e9624-82 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_0e9624-82{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_0e9624-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_0e9624-82 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_0e9624-82 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading5410_9f02eb-3c, .wp-block-kadence-advancedheading.kt-adv-heading5410_9f02eb-3c[data-kb-block=\"kb-adv-heading5410_9f02eb-3c\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading5410_9f02eb-3c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_9f02eb-3c[data-kb-block=\"kb-adv-heading5410_9f02eb-3c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_9f02eb-3c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_9f02eb-3c[data-kb-block=\"kb-adv-heading5410_9f02eb-3c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading5410_9f02eb-3c wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_9f02eb-3c\">1 Month<\/h6>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-3-color has-text-color\"><s>\u00a315<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5410_1fbe96-e7, .wp-block-kadence-advancedheading.kt-adv-heading5410_1fbe96-e7[data-kb-block=\"kb-adv-heading5410_1fbe96-e7\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading5410_1fbe96-e7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_1fbe96-e7[data-kb-block=\"kb-adv-heading5410_1fbe96-e7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_1fbe96-e7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_1fbe96-e7[data-kb-block=\"kb-adv-heading5410_1fbe96-e7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading5410_1fbe96-e7 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_1fbe96-e7\"><strong>\u00a39.99<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_1fb4ac-65:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_1fb4ac-65 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_1fb4ac-65 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_1fb4ac-65 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items5410_1fb4ac-65 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5410_1fb4ac-65 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5410_1fb4ac-65 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5410_3a1603-3b .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_3a1603-3b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_3a1603-3b kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_d243bc-7f .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_d243bc-7f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_d243bc-7f kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_a20f36-52 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_a20f36-52 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_a20f36-52 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_02eda4-4f .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_02eda4-4f .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_02eda4-4f kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_eb4f8c-b0 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_eb4f8c-b0 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_eb4f8c-b0 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze Technology<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns5410_f49a71-5c{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_f49a71-5c .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_f49a71-5c\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_064bdb-ea.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_064bdb-ea.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_064bdb-ea.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_064bdb-ea.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_064bdb-ea.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_064bdb-ea.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_064bdb-ea.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_064bdb-ea.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_064bdb-ea.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_064bdb-ea.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_064bdb-ea kt-btn-size-large kt-btn-width-type-auto kb-btn-global-outline  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/dgtlplanet.co.uk\/shop\/?add-to-cart=2026\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">BUY NOW<\/span><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_d6316d-b8 > .kt-inside-inner-col,.kadence-column5410_d6316d-b8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_d6316d-b8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_d6316d-b8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_d6316d-b8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_d6316d-b8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_d6316d-b8{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_d6316d-b8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_d6316d-b8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_d6316d-b8 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column5410_c905b1-8a > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column5410_c905b1-8a > .kt-inside-inner-col,.kadence-column5410_c905b1-8a > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column5410_c905b1-8a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_c905b1-8a > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_c905b1-8a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_c905b1-8a > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column5410_c905b1-8a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_c905b1-8a{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_c905b1-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_c905b1-8a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_c905b1-8a inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading5410_68190f-07, .wp-block-kadence-advancedheading.kt-adv-heading5410_68190f-07[data-kb-block=\"kb-adv-heading5410_68190f-07\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading5410_68190f-07 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_68190f-07[data-kb-block=\"kb-adv-heading5410_68190f-07\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_68190f-07 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_68190f-07[data-kb-block=\"kb-adv-heading5410_68190f-07\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading5410_68190f-07 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_68190f-07\">3 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center\"><s><s>\u00a3<\/s>30<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5410_a42b16-03, .wp-block-kadence-advancedheading.kt-adv-heading5410_a42b16-03[data-kb-block=\"kb-adv-heading5410_a42b16-03\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading5410_a42b16-03 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_a42b16-03[data-kb-block=\"kb-adv-heading5410_a42b16-03\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_a42b16-03 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_a42b16-03[data-kb-block=\"kb-adv-heading5410_a42b16-03\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading5410_a42b16-03 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_a42b16-03\"><strong>\u00a320<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_17eaf2-b8:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_17eaf2-b8 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_17eaf2-b8 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_17eaf2-b8 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items5410_17eaf2-b8 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5410_17eaf2-b8 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5410_17eaf2-b8 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5410_8a43b8-58 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_8a43b8-58 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_8a43b8-58 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_d1eaab-a1 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_d1eaab-a1 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_d1eaab-a1 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_726480-52 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_726480-52 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_726480-52 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_1f541b-03 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_1f541b-03 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_1f541b-03 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_d6b386-d6 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_d6b386-d6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_d6b386-d6 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze Technology<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns5410_fc923c-f8{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_fc923c-f8 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_fc923c-f8\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_ebdf5f-77.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_ebdf5f-77.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_ebdf5f-77.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_ebdf5f-77.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_ebdf5f-77.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_ebdf5f-77.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_ebdf5f-77.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_ebdf5f-77.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_ebdf5f-77.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_ebdf5f-77.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_ebdf5f-77 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-outline  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/dgtlplanet.co.uk\/shop\/?add-to-cart=1237\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">BUY NOW<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_eda6ea-35 > .kt-inside-inner-col,.kadence-column5410_eda6ea-35 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_eda6ea-35 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_eda6ea-35 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_eda6ea-35 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_eda6ea-35 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_eda6ea-35{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_eda6ea-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_eda6ea-35 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_eda6ea-35 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.kadence-column5410_809f40-47 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column5410_809f40-47 > .kt-inside-inner-col,.kadence-column5410_809f40-47 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column5410_809f40-47 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_809f40-47 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_809f40-47 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_809f40-47 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column5410_809f40-47 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_809f40-47{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_809f40-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_809f40-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_809f40-47 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading5410_b57244-fd, .wp-block-kadence-advancedheading.kt-adv-heading5410_b57244-fd[data-kb-block=\"kb-adv-heading5410_b57244-fd\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading5410_b57244-fd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_b57244-fd[data-kb-block=\"kb-adv-heading5410_b57244-fd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_b57244-fd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_b57244-fd[data-kb-block=\"kb-adv-heading5410_b57244-fd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading5410_b57244-fd wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_b57244-fd\">6 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center\"><s><s>\u00a3<\/s>45<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5410_07d0db-f0, .wp-block-kadence-advancedheading.kt-adv-heading5410_07d0db-f0[data-kb-block=\"kb-adv-heading5410_07d0db-f0\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading5410_07d0db-f0 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_07d0db-f0[data-kb-block=\"kb-adv-heading5410_07d0db-f0\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_07d0db-f0 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_07d0db-f0[data-kb-block=\"kb-adv-heading5410_07d0db-f0\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading5410_07d0db-f0 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_07d0db-f0\"><strong>\u00a340<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_7f92cf-11:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_7f92cf-11 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_7f92cf-11 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_7f92cf-11 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items5410_7f92cf-11 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5410_7f92cf-11 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5410_7f92cf-11 kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5410_dc7db0-c3 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_dc7db0-c3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_dc7db0-c3 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_b59b3a-68 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_b59b3a-68 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_b59b3a-68 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_c81f83-1d .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_c81f83-1d .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_c81f83-1d kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_e0d81e-e6 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_e0d81e-e6 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_e0d81e-e6 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_9f3043-66 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_9f3043-66 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_9f3043-66 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze Technology<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns5410_197589-98{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_197589-98 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_197589-98\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_4d4619-af.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_4d4619-af.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_4d4619-af.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_4d4619-af.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_4d4619-af.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_4d4619-af.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_4d4619-af.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_4d4619-af.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_4d4619-af.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_4d4619-af.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_4d4619-af kt-btn-size-large kt-btn-width-type-auto kb-btn-global-outline  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/dgtlplanet.co.uk\/shop\/?add-to-cart=1238\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">BUY NOW<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column5410_41bf7b-bc > .kt-inside-inner-col,.kadence-column5410_41bf7b-bc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column5410_41bf7b-bc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_41bf7b-bc > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_41bf7b-bc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_41bf7b-bc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_41bf7b-bc{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_41bf7b-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_41bf7b-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_41bf7b-bc inner-column-4\"><div class=\"kt-inside-inner-col\"><style>.kadence-column5410_daa190-75 > .kt-inside-inner-col{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;}.kadence-column5410_daa190-75 > .kt-inside-inner-col,.kadence-column5410_daa190-75 > .kt-inside-inner-col:before{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}.kadence-column5410_daa190-75 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column5410_daa190-75 > .kt-inside-inner-col{flex-direction:column;}.kadence-column5410_daa190-75 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column5410_daa190-75 > .kt-inside-inner-col{background-color:var(--global-palette9, #ffffff);}.kadence-column5410_daa190-75 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column5410_daa190-75{position:relative;}@media all and (max-width: 1024px){.kadence-column5410_daa190-75 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column5410_daa190-75 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column5410_daa190-75 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading5410_a9989d-ed, .wp-block-kadence-advancedheading.kt-adv-heading5410_a9989d-ed[data-kb-block=\"kb-adv-heading5410_a9989d-ed\"]{margin-bottom:-5px;text-align:center;font-size:16px;font-weight:700;font-style:normal;text-transform:uppercase;}.wp-block-kadence-advancedheading.kt-adv-heading5410_a9989d-ed mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_a9989d-ed[data-kb-block=\"kb-adv-heading5410_a9989d-ed\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_a9989d-ed img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_a9989d-ed[data-kb-block=\"kb-adv-heading5410_a9989d-ed\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading5410_a9989d-ed wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_a9989d-ed\">12 Months<\/h6>\n\n\n\n<p class=\"has-text-align-center\"><s><s>\u00a3<\/s>70<\/s><\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading5410_8b4fa7-40, .wp-block-kadence-advancedheading.kt-adv-heading5410_8b4fa7-40[data-kb-block=\"kb-adv-heading5410_8b4fa7-40\"]{margin-top:-50px;margin-bottom:0px;text-align:center;font-size:40px;font-style:normal;font-family:Arial, Helvetica, sans-serif;}.wp-block-kadence-advancedheading.kt-adv-heading5410_8b4fa7-40 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading5410_8b4fa7-40[data-kb-block=\"kb-adv-heading5410_8b4fa7-40\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading5410_8b4fa7-40 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading5410_8b4fa7-40[data-kb-block=\"kb-adv-heading5410_8b4fa7-40\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h4 class=\"kt-adv-heading5410_8b4fa7-40 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading5410_8b4fa7-40\"><strong>\u00a350<\/strong><\/h4>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_b05338-8c:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_b05338-8c ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_b05338-8c ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items5410_b05338-8c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items5410_b05338-8c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items5410_b05338-8c ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{font-size:14px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items5410_b05338-8c kt-svg-icon-list-columns-1 aligncenter\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-5410_3a6d5b-af .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_3a6d5b-af .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_3a6d5b-af kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">High video quality<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_bbca62-84 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_bbca62-84 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_bbca62-84 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">All Devices<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_14e3bf-f3 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_14e3bf-f3 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_14e3bf-f3 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">TV Guide (EPG)<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_0231a5-da .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_0231a5-da .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_0231a5-da kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Free Updates<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-5410_cde8b3-25 .kt-svg-icon-list-single{font-size:20px !important;color:#2ab499 !important;}.kt-svg-icon-list-item-5410_cde8b3-25 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-5410_cde8b3-25 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_checkCircle kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 11.08V12a10 10 0 1 1-5.93-9.14\"\/><polyline points=\"22 4 12 14.01 9 11.01\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Anti-Freeze Technology<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns5410_d3861b-da{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_d3861b-da .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_d3861b-da\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_ca2292-f9.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_ca2292-f9.kb-button{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);font-weight:bold;border-top-left-radius:11px;border-top-right-radius:11px;border-bottom-right-radius:11px;border-bottom-left-radius:11px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_ca2292-f9.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_ca2292-f9.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette2, #2B6CB0);border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_ca2292-f9.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_ca2292-f9.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_ca2292-f9.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_ca2292-f9.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_ca2292-f9.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_ca2292-f9.kb-button:focus{border-top-color:rgba(68, 68, 68, 0);border-top-style:solid;border-right-color:rgba(68, 68, 68, 0);border-right-style:solid;border-bottom-color:rgba(68, 68, 68, 0);border-bottom-style:solid;border-left-color:rgba(68, 68, 68, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_ca2292-f9 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-outline  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-kadence-singlebtn\" href=\"https:\/\/dgtlplanet.co.uk\/shop\/?add-to-cart=1239\" rel=\" nofollow\"><span class=\"kt-btn-inner-text\">BUY NOW<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div>\n<\/div>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kt-btns5410_43b695-ff, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns5410_43b695-ff, .wp-block-kadence-advancedbtn.kb-btns5410_43b695-ff, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns5410_43b695-ff{margin-top:-40px;margin-bottom:-50px;}.wp-block-kadence-advancedbtn.kb-btns5410_43b695-ff{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_43b695-ff .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_43b695-ff\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_bfd6a5-58.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_bfd6a5-58.kb-button{color:var(--global-palette1, #3182CE);background:var(--global-palette9, #ffffff);font-weight:bold;border-top-left-radius:25px;border-top-right-radius:25px;border-bottom-right-radius:25px;border-bottom-left-radius:25px;border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_bfd6a5-58.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_bfd6a5-58.kb-button:focus{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-top-color:rgba(178, 85, 198, 0);border-top-style:solid;border-right-color:rgba(178, 85, 198, 0);border-right-style:solid;border-bottom-color:rgba(178, 85, 198, 0);border-bottom-style:solid;border-left-color:rgba(178, 85, 198, 0);border-left-style:solid;}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_bfd6a5-58.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}}@media all and (max-width: 1024px){.wp-block-kadence-advancedbtn .kb-btn5410_bfd6a5-58.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_bfd6a5-58.kb-button:focus{border-top-color:rgba(178, 85, 198, 0);border-top-style:solid;border-right-color:rgba(178, 85, 198, 0);border-right-style:solid;border-bottom-color:rgba(178, 85, 198, 0);border-bottom-style:solid;border-left-color:rgba(178, 85, 198, 0);border-left-style:solid;}}@media all and (max-width: 767px){.wp-block-kadence-advancedbtn .kb-btn5410_bfd6a5-58.kb-button{border-top-color:rgba(85, 85, 85, 0);border-top-style:solid;border-right-color:rgba(85, 85, 85, 0);border-right-style:solid;border-bottom-color:rgba(85, 85, 85, 0);border-bottom-style:solid;border-left-color:rgba(85, 85, 85, 0);border-left-style:solid;}.wp-block-kadence-advancedbtn .kb-btn5410_bfd6a5-58.kb-button:hover, .wp-block-kadence-advancedbtn .kb-btn5410_bfd6a5-58.kb-button:focus{border-top-color:rgba(178, 85, 198, 0);border-top-style:solid;border-right-color:rgba(178, 85, 198, 0);border-right-style:solid;border-bottom-color:rgba(178, 85, 198, 0);border-bottom-style:solid;border-left-color:rgba(178, 85, 198, 0);border-left-style:solid;}}<\/style><a class=\"kb-button kt-button button kb-btn5410_bfd6a5-58 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-false  wp-block-button__link wp-block-kadence-singlebtn\" href=\"\/shop\/\"><span class=\"kt-btn-inner-text\">More Devices<\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"has-text-align-center has-theme-palette-4-color has-text-color has-background has-large-font-size\" style=\"background-color:#edf2f700\"><strong>Testimonials from our valued clients<\/strong><\/p>\n\n\n\n<div class=\"wp-block-carousel-slider-slider\"><div class=\"carousel-slider-outer carousel-slider-outer-image-carousel carousel-slider-outer-6256\" style=\"--carousel-slider-nav-color:rgba(241,241,241,0);--carousel-slider-active-nav-color:rgba(0,209,178,0);--carousel-slider-arrow-size:48px;--carousel-slider-bullet-size:10px\">\n<div id=\"&#039;id-6256\" class=\"carousel-slider carousel-slider-6256 arrows-visibility-never dots-visibility-never arrows-outside dots-center dots-circle owl-carousel\" data-slide-type=\"image-carousel\" data-owl-settings='{\"nav\":false,\"dots\":false,\"slideBy\":1,\"stagePadding\":0,\"margin\":10,\"loop\":true,\"lazyLoad\":false,\"autoplay\":true,\"autoplayTimeout\":3000,\"autoplaySpeed\":2000,\"autoplayHoverPause\":true,\"autoWidth\":false,\"responsive\":{\"300\":{\"items\":2},\"576\":{\"items\":3},\"768\":{\"items\":3},\"1024\":{\"items\":4},\"1280\":{\"items\":4},\"1536\":{\"items\":4}}}'>\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/1.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/1.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/1.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/1-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/8.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/8.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/8.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/8-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/5.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/5.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/5.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/5-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/16.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/16.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/16.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/16-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/17.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/17.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/17.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/17-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/19.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/19.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/19.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/19-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/9.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/9.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/9.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/9-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/10.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/10.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/10.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/10-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/20.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/20.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/20.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/20-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/15.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/15.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/15.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/15-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/11.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/11.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/11.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/11-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/18.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/18.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/18.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/18-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/6.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/6.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/6.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/6-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/13.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/13.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/13.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/13-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/12.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/12.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/12.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/12-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1.jpg\" data-width=\"921\" data-height=\"2048\"><img loading=\"lazy\" decoding=\"async\" width=\"921\" height=\"2048\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1.jpg 921w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-135x300.jpg 135w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-461x1024.jpg 461w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-768x1708.jpg 768w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-691x1536.jpg 691w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-5x12.jpg 5w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2024\/01\/WhatsApp-Image-2024-01-15-at-16.02.26_3b63381b-1-700x1557.jpg 700w\" sizes=\"(max-width: 921px) 100vw, 921px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/7.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/7.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/7.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/7-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/4.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/4.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/4.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/4-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/14.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/14.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/14.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/14-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/3.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/3.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/3.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/3-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<div class=\"carousel-slider__item\">\n\t<a class=\"magnific-popup\" href=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/2.webp\" data-width=\"500\" data-height=\"1014\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"1014\" src=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/2.webp\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/2.webp 500w, https:\/\/dgtl-planet.store\/wp-content\/uploads\/2023\/06\/2-148x300.webp 148w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a><\/div>\n\n<\/div><!-- .carousel-slider-6256 -->\n<\/div><!-- .carousel-slider-outer-6256 -->\n<\/div>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns5410_5778ec-ca{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns5410_5778ec-ca .kt-button{font-weight:normal;font-style:normal;}.kt-btns5410_5778ec-ca .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns5410_5778ec-ca .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns5410_5778ec-ca .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns5410_5778ec-ca .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns5410_5778ec-ca .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns5410_5778ec-ca .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns5410_5778ec-ca .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns5410_5778ec-ca\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn5410_dbb150-a2.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn5410_dbb150-a2.kb-button{color:#ffffff;background:#27db36;border-top-left-radius:20px;border-top-right-radius:20px;border-bottom-right-radius:20px;border-bottom-left-radius:20px;box-shadow:1px 1px 2px 0px var(--global-palette4, #2D3748);}.kb-btn5410_dbb150-a2.kb-button .kb-svg-icon-wrap{font-size:34px;--kb-button-icon-size:34px;}<\/style><a class=\"kb-button kt-button button kb-btn5410_dbb150-a2 kt-btn-size-standard kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\" href=\"http:\/\/wa.me\/447307725244\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_whatsapp kt-btn-icon-side-left\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">Share your Feedback<\/span><\/a><\/div>\n\n\n\n<div style=\"height:1px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Choose A Subscription Plan 1 Month \u00a315 \u00a39.99 3 Months \u00a330 \u00a320 6 Months \u00a345 \u00a340 12 Months \u00a370 \u00a350 1 Month \u00a315 \u00a39.99 3 Months \u00a330 \u00a320 6 Months \u00a345 \u00a340 12 Months \u00a370 \u00a350 Testimonials from our valued clients<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kadence_starter_templates_imported_post":true,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"normal","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"default","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_joinchat":[],"footnotes":""},"class_list":["post-5410","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dgtl-planet.store\/danish_iptv\/wp-json\/wp\/v2\/pages\/5410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dgtl-planet.store\/danish_iptv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dgtl-planet.store\/danish_iptv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dgtl-planet.store\/danish_iptv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dgtl-planet.store\/danish_iptv\/wp-json\/wp\/v2\/comments?post=5410"}],"version-history":[{"count":8,"href":"https:\/\/dgtl-planet.store\/danish_iptv\/wp-json\/wp\/v2\/pages\/5410\/revisions"}],"predecessor-version":[{"id":7701,"href":"https:\/\/dgtl-planet.store\/danish_iptv\/wp-json\/wp\/v2\/pages\/5410\/revisions\/7701"}],"wp:attachment":[{"href":"https:\/\/dgtl-planet.store\/danish_iptv\/wp-json\/wp\/v2\/media?parent=5410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}